{"id":12006,"date":"2023-12-18T16:30:44","date_gmt":"2023-12-18T21:30:44","guid":{"rendered":"https:\/\/nanosoma.com\/microscopia-de-campo-oscuro\/"},"modified":"2025-10-15T10:11:28","modified_gmt":"2025-10-15T15:11:28","slug":"microscopia-de-campo-oscuro","status":"publish","type":"page","link":"https:\/\/nanosoma.com\/es\/microscopia-de-campo-oscuro\/","title":{"rendered":"Microscop\u00eda de campo oscuro"},"content":{"rendered":"\n\n\t<section class=\"section has-scroll-for-more\" id=\"section_791879704\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<button class=\"scroll-for-more z-5 icon absolute bottom h-center\" aria-label=\"Despl\u00e1cese para m\u00e1s\"><i class=\"icon-angle-down\" aria-hidden=\"true\" style=\"font-size:42px;\"><\/i><\/button>\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-2060587030\">\n\n\n\t<div id=\"col-1576239527\" class=\"col medium-8 small-10 large-10\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1933594635\" class=\"text\">\n\t\t\n\n<h2 style=\"font-size: 270%;\">Microscopio de Campo Oscuro de Im\u00e1genes de Sangre Observando el Efecto del Metadichol<\/h2>\n<p>Estos resultados fueron presentados por el Dr. Raghavan en la Segunda Conferencia Internacional sobre Investigaci\u00f3n y Desarrollo Farmac\u00e9uticos<\/p>\n\t\t\n<style>\n#text-1933594635 {\n  font-size: 0.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1576239527 > .col-inner {\n  padding: 40px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_791879704 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_791879704 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-684175641\">\n\n\n\t<div id=\"col-2027246441\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2><strong>\u00bfQu\u00e9 es Metadichol\u00ae?<\/strong><\/h2>\n<p>Metadichol\u00ae es una nanoemulsi\u00f3n de policosanol. El policosanol se encuentra en alimentos cotidianos como el arroz, la ca\u00f1a de az\u00facar y el trigo en su forma natural, sin procesar. Tomado en NANO SOMA\u00ae, tiene extraordinarios beneficios para la salud.  <\/p>\n<p>Para leer m\u00e1s sobre el descubrimiento del Metadichol, haz clic <a href=\"https:\/\/nanosoma.com\/es\/acerca-de\/\">aqu\u00ed<\/a>.<\/p>\n<h2><strong>\u00bfQu\u00e9 es la microscop\u00eda de campo oscuro?<\/strong><\/h2>\n<p>La Microscop\u00eda de Campo Oscuro es una forma de observar cosas extremadamente peque\u00f1as con un microscopio para poder verlas mejor. Funciona bloqueando la mayor parte de la luz que suele atravesar lo que est\u00e9s mirando. De este modo, s\u00f3lo le da la luz de los lados. Esto facilita ver cosas que normalmente son dif\u00edciles de notar.   <\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_404050442\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row show-for-medium\"  id=\"row-315082787\">\n\n\n\t<div id=\"col-1970019401\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Prueba uno<\/span>\n\t<\/a>\n\n\n\t<div id=\"gap-1936621220\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1936621220 {\n  padding-top: 10px;\n}\n@media (min-width:550px) {\n  #gap-1936621220 {\n    padding-top: 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-888357168\" class=\"text\">\n\t\t\n\n<p>Roman, el primer paciente, es un var\u00f3n sano de 22 a\u00f1os y deportista. Es joven e ilustra la sangre de una persona joven y sana. De este modo, proporciona un punto de referencia para los otros dos pacientes. Sin embargo, incluso los resultados de la microscopia de Roman muestran la presencia del virus de Epstein Barr.   <\/p>\n\t\t\n<style>\n#text-888357168 {\n  text-align: left;\n  color: rgb(0, 0, 0);\n}\n#text-888357168 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"message-box relative hide-for-medium\" style=\"padding-top:50px;padding-bottom:50px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(252, 252, 252);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle align-center\" style=\"max-width:1400px\" id=\"row-5284658\">\n\n\n\t<div id=\"col-2037571428\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Prueba uno<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-499060408\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3782407508\" class=\"text\">\n\t\t\n\n<p>Roman, el primer paciente, es un var\u00f3n sano de 22 a\u00f1os y deportista. Es joven e ilustra la sangre de una persona joven y sana. De este modo, proporciona un punto de referencia para los otros dos pacientes. Sin embargo, incluso los resultados de la microscopia de Roman muestran la presencia del virus de Epstein Barr.   <\/p>\n\t\t\n<style>\n#text-3782407508 {\n  text-align: left;\n  color: rgb(0, 0, 0);\n}\n#text-3782407508 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_404050442 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_404050442 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1731775979\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-405907368\">\n\n\n\t<div id=\"col-1916069241\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1246568075\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1246568075 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-3940309228\" class=\"text\">\n\t\t\n\n<h1>Pre-Metadichol<\/h1>\n\t\t\n<style>\n#text-3940309228 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1369335060\" class=\"text\">\n\t\t\n\n<p>Estas im\u00e1genes muestran la muestra de sangre de Roman antes de tomar Metadichol a trav\u00e9s de NANO SOMA\u00ae L\u00edquido. Sus c\u00e9lulas sangu\u00edneas parecen sanas, redondas y bien espaciadas. <\/p>\n\t\t\n<style>\n#text-1369335060 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-small\"  id=\"row-1627588981\">\n\n\n\t<div id=\"col-640277162\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_784635781\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_784635781 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-973486507\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_432598271\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_432598271 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1839645801\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1721498488\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1721498488 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-3415340739\" class=\"text\">\n\t\t\n\n<p>En este resultado, sin embargo, estaba presente el virus de Epstein Barr (VEB). Esto se ve en los peque\u00f1os puntos blancos del interior de las c\u00e9lulas. La aglutinaci\u00f3n de c\u00e9lulas es frecuente cuando hay una infecci\u00f3n por VEB.  <\/p>\n\t\t\n<style>\n#text-3415340739 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle align-center\"  id=\"row-1665026664\">\n\n\n\t<div id=\"col-1393503018\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1978927529\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1978927529 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-725941699\" class=\"text\">\n\t\t\n\n<h1>Post-Metadichol<br><\/h1>\n\t\t\n<style>\n#text-725941699 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3405064215\" class=\"text\">\n\t\t\n\n<p>Los siguientes resultados muestran la sangre de Roman 20 minutos despu\u00e9s de tomar s\u00f3lo tres gotas de Metadichol (por v\u00eda oral). Estos resultados muestran una motilidad activa de los gl\u00f3bulos rojos. El examen normal de la sangre siempre muestra gl\u00f3bulos rojos est\u00e1ticos. Las c\u00e9lulas parecen normales aqu\u00ed, como en las primeras im\u00e1genes.   <\/p>\n\t\t\n<style>\n#text-3405064215 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-2136604256\">\n\n\n\t<div id=\"col-536422934\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div style=\"width: 568px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12006-1\" width=\"568\" height=\"320\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/Post-Metadichol-1.mp4?_=1\" \/><a href=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/Post-Metadichol-1.mp4\">https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/Post-Metadichol-1.mp4<\/a><\/video><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1228777761\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div style=\"width: 568px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12006-2\" width=\"568\" height=\"320\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/20-mins-post-Metadichol-1.mp4?_=2\" \/><a href=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/20-mins-post-Metadichol-1.mp4\">https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/20-mins-post-Metadichol-1.mp4<\/a><\/video><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-2009600914\" class=\"text\">\n\t\t\n\n<p>En los v\u00eddeos anteriores, puedes ver c\u00f3mo el Metadichol impuls\u00f3 lo que podr\u00eda llamarse una \u00absuperautopista sangu\u00ednea\u00bb en el organismo, con una motilidad activa considerable.<\/p>\n\t\t\n<style>\n#text-2009600914 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle\"  id=\"row-1971599717\">\n\n\n\t<div id=\"col-826833623\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1622721969\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"465\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2025\/06\/Post-Metadichol2.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2025\/06\/Post-Metadichol2.png 750w, https:\/\/nanosoma.com\/wp-content\/uploads\/2025\/06\/Post-Metadichol2-300x186.png 300w, https:\/\/nanosoma.com\/wp-content\/uploads\/2025\/06\/Post-Metadichol2-510x316.png 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1622721969 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1521101359\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>En esta secci\u00f3n de la muestra de sangre, puedes ver una deformaci\u00f3n\/destrucci\u00f3n repentina de algunos gl\u00f3bulos rojos. Esto es muy poco habitual en una muestra de sangre sana. Es el resultado de la muerte de las c\u00e9lulas despu\u00e9s de que el Metadichol haya incitado al organismo a eliminar la infecci\u00f3n encerrada en la c\u00e9lula. Estas c\u00e9lulas muertas no se encontraban en ninguna parte de la primera muestra.   <\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-middle\"  id=\"row-1248054474\">\n\n\n\t<div id=\"col-148463464\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1976401632\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"462\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/Post-Metadichol1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/Post-Metadichol1.png 750w, https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/Post-Metadichol1-300x185.png 300w, https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/Post-Metadichol1-510x314.png 510w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1976401632 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1254919649\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Aqu\u00ed se pueden ver los restos de la infecci\u00f3n por Epstein Barr, as\u00ed como las c\u00e9lulas muertas dentro de las cuales estaban encerrados.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-689822529\">\n\n\n\t<div id=\"col-1539546232\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/nanosoma.com\/es\/comprar-ahora\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\" >\n\t\t<span>COMPRAR AHORA<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1731775979 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1731775979 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row show-for-medium\"  id=\"row-754252930\">\n\n\n\t<div id=\"col-422186764\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"#testwo\" class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>TEstres dos<\/span>\n\t<\/a>\n\n\n\t<div id=\"text-4268782820\" class=\"text\">\n\t\t\n\n<p>La siguiente prueba sigue mostrando los resultados del Metadichol en muestras de sangre viva.  <\/p>\n<p>Se tom\u00f3 una muestra de sangre antes de tomar NANO SOMA L\u00edquido. A continuaci\u00f3n, el paciente tom\u00f3 seis pulverizaciones de NANO SOMA. Veintitr\u00e9s minutos despu\u00e9s de la absorci\u00f3n, se volvieron a examinar las muestras de sangre.  <\/p>\n\t\t\n<style>\n#text-4268782820 {\n  text-align: left;\n  color: rgb(0, 0, 0);\n}\n#text-4268782820 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_1679942161\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"message-box relative hide-for-medium\" style=\"padding-top:32px;padding-bottom:32px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(252, 252, 252);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle align-center\" style=\"max-width:1400px\" id=\"row-728420595\">\n\n\n\t<div id=\"col-1462045582\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"#testwo\" class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>TEstres dos<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-208631525\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1340220043\" class=\"text\">\n\t\t\n\n<p>La siguiente prueba sigue mostrando los resultados del Metadichol en muestras de sangre viva.  <\/p>\n<p>Se tom\u00f3 una muestra de sangre antes de tomar NANO SOMA L\u00edquido. A continuaci\u00f3n, el paciente tom\u00f3 seis pulverizaciones de NANO SOMA. Veintitr\u00e9s minutos despu\u00e9s de la absorci\u00f3n, se volvieron a examinar las muestras de sangre.  <\/p>\n\t\t\n<style>\n#text-1340220043 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1679942161 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n  background-color: #273647;\n}\n@media (min-width:550px) {\n  #section_1679942161 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-236324386\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-236324386 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2217641296\" class=\"text\">\n\t\t\n\n<h1>Pre-Metadichol<br><\/h1>\n\t\t\n<style>\n#text-2217641296 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle\"  id=\"row-2030183520\">\n\n\n\t<div id=\"col-120192536\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2099557128\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"264\" height=\"184\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/F-53ImageA.pre-metadichol.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2099557128 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-66712037\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>En este caso, los gl\u00f3bulos rojos est\u00e1n anormalmente apilados en largas cadenas.  <\/p>\n<p>Este apilamiento reduce dr\u00e1sticamente la superficie \u00fatil de gl\u00f3bulos rojos y su movimiento independiente, restringiendo gravemente la capacidad de los gl\u00f3bulos rojos para transportar ox\u00edgeno\/informaci\u00f3n por todo el cuerpo.<\/p>\n<p>Adem\u00e1s, el apilamiento apretado hace casi imposible observar cualquier actividad\/inclusi\u00f3n dentro de los gl\u00f3bulos rojos.<\/p>\n<p>La zona oscura llena de objetos azulados, largos y cristalinos, parecidos a hilos, indica estr\u00e9s oxidativo.<\/p>\n<p>Cada parte de la primera muestra de sangre ten\u00eda un fondo claramente visible lleno de estos objetos est\u00e1ticos.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-752339828\" class=\"text\">\n\t\t\n\n<h1>Post-Metadichol<br><\/h1>\n\t\t\n<style>\n#text-752339828 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle\"  id=\"row-796281839\">\n\n\n\t<div id=\"col-253849461\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_390800920\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"181\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/F-53ImageB.post-metadichol.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_390800920 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-916687625\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Veintitr\u00e9s minutos despu\u00e9s de tomar Metadichol, los gl\u00f3bulos rojos son repentinamente libres para moverse de forma independiente, con la superficie \u00f3ptima resultante ahora visible. Observa tambi\u00e9n la COMPLETA ausencia de estr\u00e9s oxidativo en el fondo, que no se encontraba en ninguna parte de la segunda muestra de sangre. <\/p>\n<p>La paciente se qued\u00f3 estupefacta al ver este cambio, exclamando que nunca hab\u00eda visto nada actuar tan r\u00e1pido ni tan a fondo.<\/p>\n<p>Otras observaciones de la paciente fueron:<br>&#8211; Sensaci\u00f3n repentina de luz en el cuerpo.<br>&#8211; Claridad repentina de pensamiento.<br>&#8211; Hormigueo sutil y sensaci\u00f3n de movimiento en el cuerpo.<br>Estas observaciones se produjeron s\u00f3lo 10 minutos despu\u00e9s de seis pulverizaciones de NANO SOMA.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row show-for-medium\"  id=\"row-2137257616\">\n\n\n\t<div id=\"col-231010544\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Prueba tres<\/span>\n\t<\/a>\n\n\n\t<div id=\"text-371347915\" class=\"text\">\n\t\t\n\n<p>Este paciente, M-62, padece varios problemas de salud: Diabetes de tipo 1, hipertensi\u00f3n, infecci\u00f3n por el virus de Epstein Barr (fiebre glandular, etc.). Inform\u00f3 de que su tensi\u00f3n arterial puede llegar a 260\/120, que es un factor enormemente debilitante aparte de la diabetes. De nuevo, se tom\u00f3 una muestra de sangre antes de seis pulverizaciones de NANO SOMA y otra 23 minutos despu\u00e9s de tomar NANO SOMA.  <\/p>\n\t\t\n<style>\n#text-371347915 {\n  text-align: left;\n  color: rgb(0, 0, 0);\n}\n#text-371347915 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t<section class=\"section\" id=\"section_1429876269\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-307383639\">\n\n\n\t<div id=\"col-713677131\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/nanosoma.com\/es\/comprar-ahora\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\" >\n\t\t<span>COMPRAR AHORA<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"message-box relative hide-for-medium\" style=\"padding-top:50px;padding-bottom:50px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(252, 252, 252);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle align-center\" style=\"max-width:1400px\" id=\"row-866062093\">\n\n\n\t<div id=\"col-111067231\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Prueba tres<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-97456150\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-662823171\" class=\"text\">\n\t\t\n\n<p>Este paciente, M-62, padece varios problemas de salud: Diabetes de tipo 1, hipertensi\u00f3n, infecci\u00f3n por el virus de Epstein Barr (fiebre glandular, etc.). Inform\u00f3 de que su tensi\u00f3n arterial puede llegar a 260\/120, que es un factor enormemente debilitante aparte de la diabetes. De nuevo, se tom\u00f3 una muestra de sangre antes de seis pulverizaciones de NANO SOMA y otra 23 minutos despu\u00e9s de tomar NANO SOMA.  <\/p>\n\t\t\n<style>\n#text-662823171 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1429876269 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1429876269 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1715264334\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-2004793742\">\n\n\n\t<div id=\"col-515354464\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1565128983\" class=\"text\">\n\t\t\n\n<h1>Pre-Metadichol<br><\/h1>\n\t\t\n<style>\n#text-1565128983 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3559731309\" class=\"text\">\n\t\t\n\n<p>Puede verse una clara aglutinaci\u00f3n de los gl\u00f3bulos rojos con numerosos puntitos, que indican la presencia del virus de Epstein Barr. No se observ\u00f3 ninguna motilidad de los gl\u00f3bulos rojos: parec\u00edan estar unidos en grandes grupos. <\/p>\n\t\t\n<style>\n#text-3559731309 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-middle align-center\"  id=\"row-1614843835\">\n\n\n\t<div id=\"col-1790016967\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1971911464\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:320px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"175\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/M-62ImageA.Pre-metadichol.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1971911464 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-716688985\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div style=\"width: 568px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12006-3\" width=\"568\" height=\"320\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/01\/F-53-Before.mp4?_=3\" \/><a href=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/01\/F-53-Before.mp4\">https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/01\/F-53-Before.mp4<\/a><\/video><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-46007048\">\n\n\n\t<div id=\"col-1838165231\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2251325578\" class=\"text\">\n\t\t\n\n<h1>Post-Metadichol<br><\/h1>\n\t\t\n<style>\n#text-2251325578 {\n  font-size: 1.65rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2959948061\" class=\"text\">\n\t\t\n\n<p>Al cabo de 23 minutos, se extrajo otra gota de sangre, y la imagen muestra una ausencia espectacular de los puntos blancos que representan el virus de Epstein Barr y una separaci\u00f3n de todos los gl\u00f3bulos rojos. Los gl\u00f3bulos rojos del paciente tambi\u00e9n mostraban una r\u00e1pida motilidad en todas partes de la pantalla. <\/p>\n\t\t\n<style>\n#text-2959948061 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-middle\"  id=\"row-338371061\">\n\n\n\t<div id=\"col-2006852672\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_605730435\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:320px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"177\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2023\/12\/M-62ImageB.Post-metadichol.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_605730435 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1701043277\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div style=\"width: 568px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-12006-4\" width=\"568\" height=\"320\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/F-53-After-1.mp4?_=4\" \/><a href=\"https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/F-53-After-1.mp4\">https:\/\/nanosoma.com\/wp-content\/uploads\/2024\/01\/F-53-After-1.mp4<\/a><\/video><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1480003026\">\n\n\n\t<div id=\"col-1688602022\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/nanosoma.com\/es\/comprar-ahora\/\" target=\"_blank\" class=\"button primary is-larger\" rel=\"noopener\" >\n\t\t<span>COMPRAR AHORA<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row show-for-small\"  id=\"row-93297607\">\n\n\n\t<div id=\"col-174823832\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Conclusi\u00f3n<\/span>\n\t<\/a>\n\n\n\t<div id=\"text-3851914606\" class=\"text\">\n\t\t\n\n<p>Este breve informe dej\u00f3 claro a todos los presentes que el Metadichol afecta r\u00e1pidamente a la sangre humana y al sistema circulatorio. Parece que funciona de forma diferente para cada persona, seg\u00fan sus necesidades. <\/p>\n\t\t\n<style>\n#text-3851914606 {\n  color: rgb(0, 0, 0);\n}\n#text-3851914606 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1715264334 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1715264334 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_479531725\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"message-box relative hide-for-medium\" style=\"padding-top:50px;padding-bottom:50px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(252, 252, 252);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row align-middle align-center\" style=\"max-width:1400px\" id=\"row-181389704\">\n\n\n\t<div id=\"col-1635732644\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-larger\" style=\"border-radius:99px;\">\n\t\t<span>Conclusi\u00f3n<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1045878893\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p>Este breve informe dej\u00f3 claro a todos los presentes que el Metadichol afecta r\u00e1pidamente a la sangre humana y al sistema circulatorio. Parece que funciona de forma diferente para cada persona, seg\u00fan sus necesidades. <\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_479531725 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_479531725 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"bwfblock_default_font":"","footnotes":""},"class_list":["post-12006","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/pages\/12006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/comments?post=12006"}],"version-history":[{"count":2,"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/pages\/12006\/revisions"}],"predecessor-version":[{"id":12079,"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/pages\/12006\/revisions\/12079"}],"wp:attachment":[{"href":"https:\/\/nanosoma.com\/es\/wp-json\/wp\/v2\/media?parent=12006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}